{"id":3060,"date":"2016-05-09T20:21:38","date_gmt":"2016-05-09T20:21:38","guid":{"rendered":"https:\/\/ccla.org\/?p=3060"},"modified":"2021-09-15T19:28:07","modified_gmt":"2021-09-15T19:28:07","slug":"loku-inquest-must-address-bias-in-policing","status":"publish","type":"post","link":"https:\/\/ccla.org\/fr\/legalite\/loku-inquest-must-address-bias-in-policing\/","title":{"rendered":"L&#039;enqu\u00eate Loku doit s&#039;attaquer aux biais dans les services de police"},"content":{"rendered":"<div id=\"fws_6a04323243acc\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a043232441cc\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: rgba(0,0,0,0.3); background: linear-gradient(to bottom,rgba(0,0,0,0.3) 0%,rgba(238,238,238,0.01) 100%);  opacity: 0.5; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a0432324453c\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"4%\" data-bottom-percent=\"4%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section post-links\"  style=\"padding-top: calc(100vw * 0.04); padding-bottom: calc(100vw * 0.04); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<div class=\"entry-meta\">\n<p><span class=\"posted-on\"><time class=\"entry-date published\" datetime=\"2016-05-09T12:08:27-04:00\">9 mai 2016<\/time><\/span><\/p>\n<\/div>\n<div class=\"shapely-content\">\n<p><em>Ce qui suit est une r\u00e9impression d&#039;une lettre envoy\u00e9e par des organisations et des individus concern\u00e9s, y compris l&#039;ACLC, au Dr James Andrews, coroner r\u00e9gional principal pour la r\u00e9gion du Centre, bureau de l&#039;Est de Toronto.<\/em><\/p>\n<p>Cher Dr Edwards :<\/p>\n<p>En tant que groupe d&#039;organisations et d&#039;individus concern\u00e9s, nous vous soumettons ce m\u00e9moire concernant la port\u00e9e de l&#039;enqu\u00eate sur la mort d&#039;Andrew Loku, qui a \u00e9t\u00e9 abattu par un membre du service de police de Toronto.<\/p>\n<p>Nous pensons qu&#039;il est imp\u00e9ratif que l&#039;enqu\u00eate tienne compte du r\u00f4le et de l&#039;impact des id\u00e9es et des attitudes conscientes ou inconscientes envers les personnes ayant des probl\u00e8mes de sant\u00e9 mentale et de race (en particulier le racisme anti-noir) dans les actions polici\u00e8res. De plus, ces questions devraient \u00eatre examin\u00e9es s\u00e9par\u00e9ment et de mani\u00e8re intersectionnelle afin de mieux comprendre comment elles influencent les d\u00e9cisions et les r\u00e9ponses des policiers sur les lieux.<\/p>\n<p>Nous comprenons que les questions auxquelles vous tenterez de r\u00e9pondre sont :<\/p>\n<ol>\n<li>Qui \u00e9tait le d\u00e9funt ?<\/li>\n<li>O\u00f9 est-il mort?<\/li>\n<li>Quand est-il mort?<\/li>\n<li>Comment le d\u00e9c\u00e8s est-il survenu (c.-\u00e0-d. cause m\u00e9dicale)\u00a0?<\/li>\n<li>Par quels moyens le d\u00e9c\u00e8s est-il survenu ?<\/li>\n<\/ol>\n<p>Nous estimons respectueusement que pour faire des recommandations qui auront un impact et pour r\u00e9pondre aux cinq questions de l&#039;enqu\u00eate Loku, il sera important de comprendre la culture et la formation polici\u00e8res en vigueur, et comment celles-ci influent sur les perceptions polici\u00e8res des personnes noires et des personnes vivant avec des probl\u00e8mes de sant\u00e9 mentale.<\/p>\n<p>Il existe d&#039;importantes recherches et d&#039;autres preuves documentaires que la discrimination syst\u00e9mique, le racisme anti-noir et le profilage racial ont une incidence sur les r\u00e9sultats des interactions entre la police et la communaut\u00e9 dans des circonstances individuelles. Et, il existe des donn\u00e9es pour \u00e9tayer la conclusion qu&#039;un nombre disproportionn\u00e9 d&#039;hommes noirs vivant avec des probl\u00e8mes de sant\u00e9 mentale sont abattus par la police. Cependant, \u00e0 ce jour, et au meilleur de notre connaissance, \u00e0 part l&#039;enqu\u00eate Carby actuellement en cours, aucune enqu\u00eate du coroner n&#039;a d\u00e9lib\u00e9r\u00e9ment abord\u00e9 la question de la race et du racisme anti-noir dans la mort de personnes noires aux mains de la police.<\/p>\n<p>Le profilage racial a \u00e9t\u00e9 reconnu \u00e0 maintes reprises par les cours, les tribunaux, les universitaires, la communaut\u00e9, les m\u00e9dias et la police elle-m\u00eame comme un probl\u00e8me dans le maintien de l&#039;ordre. En effet, la Commission des services policiers de Toronto et le service de police de Toronto se sont eux-m\u00eames pr\u00e9occup\u00e9s de la question des services policiers de discrimination raciale et ont envisag\u00e9 un certain nombre de mesures pour y faire face, notamment une formation obligatoire sur les pr\u00e9jug\u00e9s implicites.<\/p>\n<p>Nous vous soumettons respectueusement que la seule fa\u00e7on de comprendre compl\u00e8tement \u00ab par quels moyens \u00bb M. Loku est d\u00e9c\u00e9d\u00e9 est donc de consid\u00e9rer l&#039;impact du profilage racial dans ce cas.<\/p>\n<p>De plus, nous soutenons qu&#039;il existe une intersection socialement significative entre la race et la sant\u00e9 mentale qui peut influer sur les d\u00e9cisions des agents concernant le recours \u00e0 la force. Les personnes noires souffrant de probl\u00e8mes de sant\u00e9 mentale peuvent \u00eatre plus susceptibles d&#039;\u00eatre pr\u00e9sent\u00e9es comme un risque pour la s\u00e9curit\u00e9\/la s\u00e9curit\u00e9 que les autres personnes. Certains craignent que la police soit plus susceptible de recourir \u00e0 la force dans ses interactions avec les Afro-Canadiens en raison de st\u00e9r\u00e9otypes qui incluent la croyance qu&#039;ils sont enclins \u00e0 la violence. La mort aux mains de la police de plusieurs personnes noires vivant avec des probl\u00e8mes de sant\u00e9 mentale a renforc\u00e9 cette croyance. \u00c0 tel point, en fait, qu&#039;en 1999, des organismes de sant\u00e9 mentale, des organismes de lutte contre le racisme, la commission des services policiers et le service de police ont organis\u00e9 conjointement une grande conf\u00e9rence intitul\u00e9e \u00ab Sauver des vies : Alternatives \u00e0 l&#039;utilisation de la force l\u00e9tale \u00bb. Pourtant, les morts ont continu\u00e9. Si l&#039;enqu\u00eate doit aider \u00e0 pr\u00e9venir de futurs d\u00e9c\u00e8s, nous pensons qu&#039;il est essentiel que l&#039;enqu\u00eate tienne \u00e9galement compte des preuves sur la question de l&#039;intersectionnalit\u00e9 de la sant\u00e9 mentale et de la race dans la mort de M. Loku, en faisant sp\u00e9cifiquement r\u00e9f\u00e9rence \u00e0 son identit\u00e9 racialis\u00e9e en tant qu&#039;homme noir. du Soudan du Sud.<\/p>\n<p>Enfin, comme les questions que nous vous exhortons \u00e0 consid\u00e9rer sont historiquement et juridiquement complexes, il serait crucial que l&#039;avocat du coroner et d&#039;autres personnes nomm\u00e9es ou affect\u00e9es \u00e0 l&#039;enqu\u00eate aient les comp\u00e9tences et l&#039;exp\u00e9rience requises pour examiner l&#039;impact de la race et du racisme sur les interactions entre la police et la communaut\u00e9. Cela est n\u00e9cessaire pour garantir que les preuves appropri\u00e9es et n\u00e9cessaires peuvent \u00eatre prises en compte, les facteurs qui ont contribu\u00e9 au d\u00e9c\u00e8s peuvent \u00eatre analys\u00e9s en profondeur - y compris une analyse raciale - et des recommandations peuvent \u00eatre formul\u00e9es qui auraient un impact significatif sur les d\u00e9fis complexes \u00e0 surmonter pour pr\u00e9venir les d\u00e9c\u00e8s futurs.<\/p>\n<p>Ainsi, pour que les recommandations am\u00e9liorent v\u00e9ritablement la probabilit\u00e9 de pr\u00e9venir des d\u00e9c\u00e8s similaires \u00e0 l&#039;avenir, nous vous exhortons \u00e0 reconna\u00eetre et \u00e0 inclure l&#039;intersection entre la race, les probl\u00e8mes de sant\u00e9 mentale et le racisme anti-noir dans la formulation de la port\u00e9e de cette enqu\u00eate.<\/p>\n<p>En terminant, nous tenons \u00e0 vous assurer que nous ne tirons aucune conclusion sur les conclusions de l&#039;enqu\u00eate. Nous pensons que pour restaurer la confiance du public dans les enqu\u00eates sur les d\u00e9c\u00e8s de personnes noires et ayant des probl\u00e8mes de sant\u00e9 mentale lors de rencontres avec la police, il doit y avoir une exploration compl\u00e8te de ces caract\u00e9ristiques de l&#039;affaire.<\/p>\n<p>Merci pour votre consid\u00e9ration. Veuillez nous contacter si nous pouvons vous aider davantage.<\/p>\n<p>Sinc\u00e8rement,<\/p>\n<p>Alok Mukherjee<br \/>\nProfesseur invit\u00e9 distingu\u00e9<br \/>\nBureau de l&#039;\u00e9quit\u00e9, de la diversit\u00e9 et de l&#039;inclusion \/ D\u00e9partement de criminologie<br \/>\nUniversit\u00e9 Ryerson<\/p>\n<h3><span style=\"color: #1e5799;\"><strong>SIGNATURE AU NOM DES PERSONNES ET ORGANISATIONS SUIVANTES\u00a0:<\/strong><\/span><\/h3>\n<p>Abdillahi<br \/>\nProfesseur adjoint, \u00c9cole de service social, Universit\u00e9 Ryerson<br \/>\nPr\u00e9sident, Conseil d&#039;administration, Across Boundaries: An Ethnoracial Mental Health Centre<\/p>\n<p>Pat Capponi<br \/>\nFacilitatrice principale, Voices from the Street<\/p>\n<p>Pat Case<br \/>\nPr\u00e9sident, Conseil d&#039;administration, Centre d&#039;assistance juridique en mati\u00e8re de droits de la personne<\/p>\n<p>Jennifer Chambers<br \/>\nDirecteur ex\u00e9cutif, Conseil d&#039;habilitation<\/p>\n<p>Lana Frado<br \/>\nDirecteur ex\u00e9cutif, Services d&#039;assistance Sound Times<\/p>\n<p>Steve Lurie<br \/>\nDirecteur ex\u00e9cutif, Association canadienne pour la sant\u00e9 mentale \u2013 succursale de Toronto<\/p>\n<p>Renu Mandhane<br \/>\nCommissaire en chef, Commission ontarienne des droits de la personne<\/p>\n<p>Kwame McKenzie<br \/>\nPDG, Institut Wellesley<\/p>\n<p>Noa Mendelsohn Aviv<br \/>\nDirectrice, Programme d&#039;\u00e9galit\u00e9, Association canadienne des libert\u00e9s civiles<\/p>\n<p>Howard Morton<br \/>\nSyndicat des avocats de l&#039;Ontario<\/p>\n<p>Anne-Marie Singh<br \/>\nProfesseur agr\u00e9g\u00e9, D\u00e9partement de criminologie, Universit\u00e9 Ryerson<\/p>\n<p>Knia Singh<br \/>\nSoci\u00e9t\u00e9 Osgoode contre les injustices institutionnelles<\/p>\n<p>cc : Dr Dirk Huyer, coroner en chef<br \/>\ncc : Premi\u00e8re ministre Kathleen Wynne<br \/>\ncc : Patrick Brown, d\u00e9put\u00e9 provincial<br \/>\ncc : Andrea Horwarth, d\u00e9put\u00e9e provinciale<br \/>\ncc : Ministre Michael Couteau<br \/>\ncc : Ministre Eric Hoskins<br \/>\ncc : Sam Erry, sous-ministre adjoint, Direction g\u00e9n\u00e9rale de la lutte contre le racisme en Ontario<br \/>\ncc: Black Lives Matter Toronto<\/p>\n<\/div>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04323244a47\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a04323244e27\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"1%\" data-bottom-percent=\"1%\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: calc(100vw * 0.01); padding-bottom: calc(100vw * 0.01); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >\u00c0 propos de l\u2019association canadienne sur les libert\u00e9s civiles<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p class=\"translation-block\">L\u2019ACLC est un organisme ind\u00e9pendant \u00e0 but non lucratif qui compte des sympathisant.e.s dans tout le pays. Fond\u00e9 en 1964, c\u2019est un organisme qui \u0153uvre \u00e0 l\u2019\u00e9chelle du Canada \u00e0 la protection des droits et des libert\u00e9s civiles de toute sa population.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les m\u00e9dias<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Pour d&#039;autres commentaires, veuillez nous contacter \u00e0\u00a0<a href=\"mailto:media@ccla.org\"><u>media@ccla.org<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les mises \u00e0 jour en direct<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Veuillez continuer \u00e0 vous r\u00e9f\u00e9rer \u00e0\u00a0<a href=\"https:\/\/ccla.org\/fr\/the-latest\/\" rel=\"noopener\">cette page<\/a>\u00a0et \u00e0 nos plateformes de m\u00e9dias sociaux. On est dessus\u00a0<a href=\"https:\/\/www.instagram.com\/cancivlib\/?hl=en\" target=\"_blank\" rel=\"noopener\"><u>Instagram<\/u><\/a>,\u00a0<a href=\"http:\/\/facebook.com\/cancivlib\/\" target=\"_blank\" rel=\"noopener\"><u>Facebook<\/u><\/a>, <a href=\"https:\/\/twitter.com\/cancivlib\" target=\"_blank\" rel=\"noopener\"><u>Twitter<\/u><\/a> et <a href=\"https:\/\/bsky.app\/profile\/cancivlib.bsky.social\" target=\"_blank\" rel=\"noopener\"><u>Ciel bleu<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>L&#039;Association canadienne des libert\u00e9s civiles (ACLC) contestera l&#039;injonction exceptionnellement large du gouvernement de la Nouvelle-\u00c9cosse limitant les manifestations dans la province.<\/p>","protected":false},"author":4,"featured_media":461,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[128,39,73,6,102,93,85,56],"tags":[],"class_list":{"0":"post-3060","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-conditions-of-confinement","8":"category-criminal-justice","9":"category-disability","10":"category-equality","11":"category-fighting-solitary-confinement","12":"category-major-cases-reports","13":"category-prisons-jails-community-supervision","14":"category-youth"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Loku Inquest Must Address Bias In Policing - CCLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccla.org\/fr\/legalite\/loku-inquest-must-address-bias-in-policing\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Loku Inquest Must Address Bias In Policing - CCLA\" \/>\n<meta property=\"og:description\" content=\"The Canadian Civil Liberties Association (CCLA)\u00a0will challenge the Government of Nova Scotia\u2019s\u00a0exceptionally broad injunction limiting protests in the province.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccla.org\/fr\/legalite\/loku-inquest-must-address-bias-in-policing\/\" \/>\n<meta property=\"og:site_name\" content=\"CCLA\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-09T20:21:38+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-15T19:28:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/police-bicycle-1920x977-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"977\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CCLA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CCLA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/\",\"url\":\"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/\",\"name\":\"Loku Inquest Must Address Bias In Policing - CCLA\",\"isPartOf\":{\"@id\":\"https:\/\/ccla.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/police-bicycle-1920x977-1.jpg\",\"datePublished\":\"2016-05-09T20:21:38+00:00\",\"dateModified\":\"2021-09-15T19:28:07+00:00\",\"author\":{\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d\"},\"breadcrumb\":{\"@id\":\"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#primaryimage\",\"url\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/police-bicycle-1920x977-1.jpg\",\"contentUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/police-bicycle-1920x977-1.jpg\",\"width\":1920,\"height\":977,\"caption\":\"Know your rights\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ccla.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CRIMINAL JUSTICE\",\"item\":\"https:\/\/ccla.org\/category\/criminal-justice\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Prisons, Jails &amp; Community Supervision\",\"item\":\"https:\/\/ccla.org\/category\/criminal-justice\/prisons-jails-community-supervision\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Conditions of Confinement\",\"item\":\"https:\/\/ccla.org\/category\/criminal-justice\/prisons-jails-community-supervision\/conditions-of-confinement\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Loku Inquest Must Address Bias In Policing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ccla.org\/#website\",\"url\":\"https:\/\/ccla.org\/\",\"name\":\"CCLA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ccla.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d\",\"name\":\"CCLA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g\",\"caption\":\"CCLA\"},\"url\":\"https:\/\/ccla.org\/fr\/author\/ccla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Loku Inquest Must Address Bias In Policing - CCLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccla.org\/fr\/legalite\/loku-inquest-must-address-bias-in-policing\/","og_locale":"fr_CA","og_type":"article","og_title":"Loku Inquest Must Address Bias In Policing - CCLA","og_description":"The Canadian Civil Liberties Association (CCLA)\u00a0will challenge the Government of Nova Scotia\u2019s\u00a0exceptionally broad injunction limiting protests in the province.","og_url":"https:\/\/ccla.org\/fr\/legalite\/loku-inquest-must-address-bias-in-policing\/","og_site_name":"CCLA","article_published_time":"2016-05-09T20:21:38+00:00","article_modified_time":"2021-09-15T19:28:07+00:00","og_image":[{"width":1920,"height":977,"url":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/police-bicycle-1920x977-1.jpg","type":"image\/jpeg"}],"author":"CCLA","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CCLA","Estimation du temps de lecture":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/","url":"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/","name":"Loku Inquest Must Address Bias In Policing - CCLA","isPartOf":{"@id":"https:\/\/ccla.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#primaryimage"},"image":{"@id":"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#primaryimage"},"thumbnailUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/police-bicycle-1920x977-1.jpg","datePublished":"2016-05-09T20:21:38+00:00","dateModified":"2021-09-15T19:28:07+00:00","author":{"@id":"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d"},"breadcrumb":{"@id":"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#primaryimage","url":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/police-bicycle-1920x977-1.jpg","contentUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/police-bicycle-1920x977-1.jpg","width":1920,"height":977,"caption":"Know your rights"},{"@type":"BreadcrumbList","@id":"https:\/\/ccla.org\/fr\/equality\/loku-inquest-must-address-bias-in-policing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ccla.org\/"},{"@type":"ListItem","position":2,"name":"CRIMINAL JUSTICE","item":"https:\/\/ccla.org\/category\/criminal-justice\/"},{"@type":"ListItem","position":3,"name":"Prisons, Jails &amp; Community Supervision","item":"https:\/\/ccla.org\/category\/criminal-justice\/prisons-jails-community-supervision\/"},{"@type":"ListItem","position":4,"name":"Conditions of Confinement","item":"https:\/\/ccla.org\/category\/criminal-justice\/prisons-jails-community-supervision\/conditions-of-confinement\/"},{"@type":"ListItem","position":5,"name":"Loku Inquest Must Address Bias In Policing"}]},{"@type":"WebSite","@id":"https:\/\/ccla.org\/#website","url":"https:\/\/ccla.org\/","name":"CCLA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccla.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d","name":"CCLA","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g","caption":"CCLA"},"url":"https:\/\/ccla.org\/fr\/author\/ccla\/"}]}},"_links":{"self":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/3060","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/comments?post=3060"}],"version-history":[{"count":1,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/3060\/revisions"}],"predecessor-version":[{"id":3061,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/3060\/revisions\/3061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media\/461"}],"wp:attachment":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media?parent=3060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/categories?post=3060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/tags?post=3060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}