{"id":2542,"date":"2018-12-19T16:30:54","date_gmt":"2018-12-19T16:30:54","guid":{"rendered":"https:\/\/ccla.org\/?p=2542"},"modified":"2021-09-22T18:21:42","modified_gmt":"2021-09-22T18:21:42","slug":"canadians-care-about-privacy-politicians-need-to-show-they-care-about-us","status":"publish","type":"post","link":"https:\/\/ccla.org\/fr\/intimite\/reforme-de-la-legislation-sur-la-protection-de-la-vie-privee\/les-canadiens-tiennent-a-leur-vie-privee-les-politiciens-doivent-montrer-quils-se-soucient-de-nous\/","title":{"rendered":"Les Canadiens se soucient de la vie priv\u00e9e, les politiciens doivent montrer qu&#039;ils se soucient de nous"},"content":{"rendered":"<div id=\"fws_6a04612fda813\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a04612fdac47\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: rgba(0,0,0,0.3); background: linear-gradient(to bottom,rgba(0,0,0,0.3) 0%,rgba(238,238,238,0.01) 100%);  opacity: 0.5; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04612fdaef7\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"4%\" data-bottom-percent=\"4%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section post-links\"  style=\"padding-top: calc(100vw * 0.04); padding-bottom: calc(100vw * 0.04); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>73% de Canadiens sont pr\u00e9occup\u00e9s ou quelque peu pr\u00e9occup\u00e9s par la fa\u00e7on dont les partis politiques utilisent les renseignements personnels selon un sondage Nanos publi\u00e9 aujourd&#039;hui\u00a0<a href=\"https:\/\/www.theglobeandmail.com\/politics\/article-canadians-concerned-about-how-facebook-political-parties-protect\/\" target=\"_blank\" rel=\"noopener\">par le Globe and Mail<\/a>.<\/p>\n<p>Alors pourquoi les partis politiques ne sont-ils pas couverts par la loi sur la protection de la vie priv\u00e9e au Canada?<\/p>\n<p>Ce n&#039;est certainement pas parce que les parties ne collectent ni n&#039;utilisent de donn\u00e9es personnelles. Chaque parti dispose d&#039;une base de donn\u00e9es des \u00e9lecteurs pour garder une trace des partisans, des donateurs, des r\u00e9sultats des frappes aux portes, en d&#039;autres termes, les informations n\u00e9cessaires pour mener des campagnes. Certaines parties donnent des applications \u00e0 leurs solliciteurs pour leur permettre de saisir des donn\u00e9es \u00e0 la vol\u00e9e. Chaque partie s&#039;appuie sur l&#039;analyse des donn\u00e9es pour aider \u00e0 la strat\u00e9gie. Et presque in\u00e9vitablement, chaque partie partage des informations avec des fournisseurs de services tiers engag\u00e9s pour faire des choses comme traiter les dons ou organiser des sondages.<\/p>\n<p>Ce n&#039;est pas non plus parce qu&#039;il existe un d\u00e9saccord g\u00e9n\u00e9ralis\u00e9 sur la question de savoir si les informations sur nos opinions politiques sont sensibles ou non et m\u00e9ritent d&#039;\u00eatre prot\u00e9g\u00e9es. Les convictions politiques sont un motif interdit de discrimination en vertu de la\u00a0<em><a href=\"https:\/\/laws-lois.justice.gc.ca\/eng\/acts\/h-6\/\" target=\"_blank\" rel=\"noopener\">Loi canadienne sur les droits de la personne<\/a><\/em>\u00a0et d&#039;autres actes de ce genre au niveau international. Dans l&#039;Union europ\u00e9enne, le r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es, qui influence le paysage de la confidentialit\u00e9 dans le monde entier, inclut \u00e9galement explicitement les opinions politiques comme une cat\u00e9gorie de donn\u00e9es \u00ab\u00a0sp\u00e9ciale\u00a0\u00bb, c&#039;est-\u00e0-dire sensible. Ce qui soul\u00e8ve un autre point\u00a0: l&#039;\u00e9chec du Canada \u00e0 inclure les partis politiques dans la loi sur la protection de la vie priv\u00e9e n&#039;est pas d\u00fb au fait que personne d&#039;autre ne le fait, car le Royaume-Uni, une grande partie de l&#039;UE et la Nouvelle-Z\u00e9lande ont tous des lois couvrant les organisations politiques.<\/p>\n<p>Il est \u00e9galement difficile de soutenir que les partis devraient \u00eatre exclus des lois sur la protection de la vie priv\u00e9e, car cela entraverait le processus d\u00e9mocratique. Nous avons l&#039;exemple parfait en Colombie-Britannique, la seule province qui a inclus les partis politiques dans sa l\u00e9gislation sur la protection de la vie priv\u00e9e depuis 2004. Les partis continuent de recueillir des informations, de mobiliser les \u00e9lecteurs et de mener des campagnes efficaces dans ce qui est sans doute l&#039;une des provinces les plus excitantes sur le plan politique en le pays.<\/p>\n<p>Et ce n&#039;est absolument pas parce que les experts pensent que c&#039;est une mauvaise id\u00e9e. Au cours de sa r\u00e9cente \u00e9tude sur les vuln\u00e9rabilit\u00e9s \u00e0 la vie priv\u00e9e dans le processus \u00e9lectoral d\u00e9mocratique du Canada, le\u00a0<a href=\"http:\/\/www.ourcommons.ca\/DocumentViewer\/en\/42-1\/ETHI\/report-17\/\" target=\"_blank\" rel=\"noopener\">Commission parlementaire sur l&#039;acc\u00e8s \u00e0 l&#039;information, la protection des renseignements personnels et l&#039;\u00e9thique<\/a>\u00a0\u00e9cout\u00e9 une longue file de t\u00e9moins et conclu que les partis politiques devraient vraiment \u00eatre couverts par une loi.<\/p>\n<p>Tous les commissaires provinciaux \u00e0 l&#039;information et \u00e0 la protection de la vie priv\u00e9e au Canada, ainsi que le commissaire f\u00e9d\u00e9ral \u00e0 la protection de la vie priv\u00e9e, sont d&#039;accord. Dans un\u00a0<a href=\"https:\/\/www.priv.gc.ca\/en\/about-the-opc\/what-we-do\/provincial-and-territorial-collaboration\/joint-resolutions-with-provinces-and-territories\/res_180913\/\" target=\"_blank\" rel=\"noopener\">r\u00e9solution conjointe publi\u00e9e le 17 septembre<\/a>, ils ont appel\u00e9 les gouvernements \u00e0 adopter une l\u00e9gislation pour r\u00e9gir l&#039;utilisation des renseignements personnels par les partis politiques, pour assurer la surveillance de ces utilisations et pour permettre aux gens d&#039;acc\u00e9der \u00e0 leurs propres informations d\u00e9tenues par les partis.<\/p>\n<p>En d&#039;autres termes, ils ont demand\u00e9 que les partis politiques soient tenus de respecter les m\u00eames principes et r\u00e8gles de confidentialit\u00e9 que les gouvernements et les entreprises qui collectent nos informations doivent suivre.<\/p>\n<p>Alors pourquoi les partis politiques ne sont-ils pas inclus dans la loi sur la protection des renseignements personnels au Canada? La r\u00e9ponse la plus simple semble \u00eatre, parce qu&#039;ils ne veulent pas l&#039;\u00eatre. Il n&#039;y a tout simplement pas la volont\u00e9 politique d&#039;y parvenir, car l&#039;effort de r\u00e9forme \u00e9lectorale du gouvernement actuel,\u00a0<a href=\"https:\/\/www.parl.ca\/LegisInfo\/BillDetails.aspx?billId=9808070&amp;Language=E\" target=\"_blank\" rel=\"noopener\">Projet de loi 76<\/a>\u00a0rend tristement clair.<\/p>\n<p>Les entreprises du secteur priv\u00e9 ne peuvent pas utiliser vos informations personnelles sans votre consentement. Les partis peuvent. Les gouvernements \u00e9lus sont limit\u00e9s dans leur capacit\u00e9 \u00e0 collecter des informations aupr\u00e8s de nous pour une raison et \u00e0 les utiliser pour une autre. Les partis politiques ne le sont pas.<\/p>\n<p>Pourquoi est-ce important? Nous vivons \u00e0 une \u00e9poque o\u00f9 nous voulons utiliser les donn\u00e9es comme une baguette magique, quelque chose que nous pouvons pointer et \u2013 pouf \u2013 la fa\u00e7on d&#039;influencer une personne ou un groupe de personnes est r\u00e9v\u00e9l\u00e9e. \u00c9videmment, nous devrions nous demander si c&#039;est vraiment ainsi que cela fonctionne, mais simplement la perception que cela pourrait signifier que chaque parti politique veut autant d&#039;informations sur nous que possible. Il est clair qu&#039;ils recherchent tous des moyens nouveaux et passionnants d&#039;en savoir plus sur nous, de nous cibler et de pr\u00e9dire notre comportement, pour avoir une longueur d&#039;avance sur leurs concurrents. Donc, c&#039;est un probl\u00e8me qu&#039;il n&#039;y ait pas de lois r\u00e9gissant jusqu&#039;o\u00f9 ils peuvent aller.<\/p>\n<p>Pour \u00eatre juste, toutes les grandes parties ont leurs propres politiques de confidentialit\u00e9. Certaines politiques ne sont pas mauvaises. Mais ce sont des r\u00e8gles que les parties \u00e9tablissent et appliquent pour elles-m\u00eames. Tout est une question de confiance dans un climat o\u00f9 il y a beaucoup de motivation pour repousser les limites et o\u00f9 la confiance du public dans l&#039;int\u00e9grit\u00e9 de nos processus politiques est fragile.<\/p>\n<p>Bien qu&#039;il n&#039;y ait aucune raison de principe pour laquelle la loi sur la protection de la vie priv\u00e9e ne devrait pas s&#039;appliquer aux partis politiques de la m\u00eame mani\u00e8re qu&#039;elle le fait \u00e0 peu pr\u00e8s tous les autres collecteurs de donn\u00e9es des secteurs public et priv\u00e9, une mise en \u0153uvre \u00e9quitable serait essentielle. Une telle l\u00e9gislation ne peut pas \u00eatre con\u00e7ue de mani\u00e8re \u00e0 handicaper un parti d&#039;opposition ou \u00e0 rendre la conformit\u00e9 disproportionn\u00e9e difficile pour les partis qui disposent de moins de ressources. Tout projet de loi doit \u00eatre soigneusement examin\u00e9, fond\u00e9 sur des principes et \u00e9quitable : aucun jeu politique ne peut \u00eatre autoris\u00e9 au nom de la protection de la vie priv\u00e9e.<\/p>\n<p>C&#039;est vraiment tr\u00e8s simple. Les partis politiques qui demandent nos votes \u2013 et nos num\u00e9ros de carte de cr\u00e9dit \u2013 devraient \u00eatre l\u00e9galement responsables du respect de nos droits \u00e0 la vie priv\u00e9e.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04612fdb235\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a04612fdb558\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"1%\" data-bottom-percent=\"1%\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: calc(100vw * 0.01); padding-bottom: calc(100vw * 0.01); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >\u00c0 propos de l\u2019association canadienne sur les libert\u00e9s civiles<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p class=\"translation-block\">L\u2019ACLC est un organisme ind\u00e9pendant \u00e0 but non lucratif qui compte des sympathisant.e.s dans tout le pays. Fond\u00e9 en 1964, c\u2019est un organisme qui \u0153uvre \u00e0 l\u2019\u00e9chelle du Canada \u00e0 la protection des droits et des libert\u00e9s civiles de toute sa population.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les m\u00e9dias<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Pour d&#039;autres commentaires, veuillez nous contacter \u00e0\u00a0<a href=\"mailto:media@ccla.org\"><u>media@ccla.org<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les mises \u00e0 jour en direct<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Veuillez continuer \u00e0 vous r\u00e9f\u00e9rer \u00e0\u00a0<a href=\"https:\/\/ccla.org\/fr\/the-latest\/\" rel=\"noopener\">cette page<\/a>\u00a0et \u00e0 nos plateformes de m\u00e9dias sociaux. On est dessus\u00a0<a href=\"https:\/\/www.instagram.com\/cancivlib\/?hl=en\" target=\"_blank\" rel=\"noopener\"><u>Instagram<\/u><\/a>,\u00a0<a href=\"http:\/\/facebook.com\/cancivlib\/\" target=\"_blank\" rel=\"noopener\"><u>Facebook<\/u><\/a>, <a href=\"https:\/\/twitter.com\/cancivlib\" target=\"_blank\" rel=\"noopener\"><u>Twitter<\/u><\/a> et <a href=\"https:\/\/bsky.app\/profile\/cancivlib.bsky.social\" target=\"_blank\" rel=\"noopener\"><u>Ciel bleu<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>73% de Canadiens sont pr\u00e9occup\u00e9s ou quelque peu pr\u00e9occup\u00e9s par la fa\u00e7on dont les partis politiques utilisent les renseignements personnels selon un sondage Nanos publi\u00e9 aujourd&#039;hui par le Globe and Mail.<\/p>","protected":false},"author":11,"featured_media":1120,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11,87],"tags":[],"class_list":{"0":"post-2542","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-privacy","8":"category-privacy-law-reform"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Canadians Care about Privacy, Politicians Need to Show They Care About Us - CCLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccla.org\/fr\/intimite\/reforme-de-la-legislation-sur-la-protection-de-la-vie-privee\/les-canadiens-tiennent-a-leur-vie-privee-les-politiciens-doivent-montrer-quils-se-soucient-de-nous\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Canadians Care about Privacy, Politicians Need to Show They Care About Us - CCLA\" \/>\n<meta property=\"og:description\" content=\"73% of Canadians are concerned or somewhat concerned about how political parties use personal information according to a Nanos poll released today\u00a0by the Globe and Mail.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccla.org\/fr\/intimite\/reforme-de-la-legislation-sur-la-protection-de-la-vie-privee\/les-canadiens-tiennent-a-leur-vie-privee-les-politiciens-doivent-montrer-quils-se-soucient-de-nous\/\" \/>\n<meta property=\"og:site_name\" content=\"CCLA\" \/>\n<meta property=\"article:published_time\" content=\"2018-12-19T16:30:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-22T18:21:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/Privacy_750x900.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"750\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Brenda McPhail\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Brenda\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Brenda McPhail\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/\",\"url\":\"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/\",\"name\":\"Canadians Care about Privacy, Politicians Need to Show They Care About Us - CCLA\",\"isPartOf\":{\"@id\":\"https:\/\/ccla.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/Privacy_750x900.jpg\",\"datePublished\":\"2018-12-19T16:30:54+00:00\",\"dateModified\":\"2021-09-22T18:21:42+00:00\",\"author\":{\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/c0ab72c13438e404cfca5f071db582f8\"},\"breadcrumb\":{\"@id\":\"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#primaryimage\",\"url\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/Privacy_750x900.jpg\",\"contentUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/Privacy_750x900.jpg\",\"width\":750,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ccla.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRIVACY\",\"item\":\"https:\/\/ccla.org\/category\/privacy\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Privacy Law Reform\",\"item\":\"https:\/\/ccla.org\/fr\/category\/privacy\/privacy-law-reform\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Canadians Care about Privacy, Politicians Need to Show They Care About Us\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ccla.org\/#website\",\"url\":\"https:\/\/ccla.org\/\",\"name\":\"CCLA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ccla.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/c0ab72c13438e404cfca5f071db582f8\",\"name\":\"Brenda McPhail\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b88e2b9b83f05dd6b511990cc78ba746?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b88e2b9b83f05dd6b511990cc78ba746?s=96&d=blank&r=g\",\"caption\":\"Brenda McPhail\"},\"sameAs\":[\"https:\/\/x.com\/Brenda\"],\"url\":\"https:\/\/ccla.org\/fr\/author\/brenda\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Canadians Care about Privacy, Politicians Need to Show They Care About Us - CCLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccla.org\/fr\/intimite\/reforme-de-la-legislation-sur-la-protection-de-la-vie-privee\/les-canadiens-tiennent-a-leur-vie-privee-les-politiciens-doivent-montrer-quils-se-soucient-de-nous\/","og_locale":"fr_CA","og_type":"article","og_title":"Canadians Care about Privacy, Politicians Need to Show They Care About Us - CCLA","og_description":"73% of Canadians are concerned or somewhat concerned about how political parties use personal information according to a Nanos poll released today\u00a0by the Globe and Mail.","og_url":"https:\/\/ccla.org\/fr\/intimite\/reforme-de-la-legislation-sur-la-protection-de-la-vie-privee\/les-canadiens-tiennent-a-leur-vie-privee-les-politiciens-doivent-montrer-quils-se-soucient-de-nous\/","og_site_name":"CCLA","article_published_time":"2018-12-19T16:30:54+00:00","article_modified_time":"2021-09-22T18:21:42+00:00","og_image":[{"width":750,"height":900,"url":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/Privacy_750x900.jpg","type":"image\/jpeg"}],"author":"Brenda McPhail","twitter_card":"summary_large_image","twitter_creator":"@Brenda","twitter_misc":{"\u00c9crit par":"Brenda McPhail","Estimation du temps de lecture":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/","url":"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/","name":"Canadians Care about Privacy, Politicians Need to Show They Care About Us - CCLA","isPartOf":{"@id":"https:\/\/ccla.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#primaryimage"},"image":{"@id":"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#primaryimage"},"thumbnailUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/Privacy_750x900.jpg","datePublished":"2018-12-19T16:30:54+00:00","dateModified":"2021-09-22T18:21:42+00:00","author":{"@id":"https:\/\/ccla.org\/#\/schema\/person\/c0ab72c13438e404cfca5f071db582f8"},"breadcrumb":{"@id":"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#primaryimage","url":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/Privacy_750x900.jpg","contentUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/05\/Privacy_750x900.jpg","width":750,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/ccla.org\/fr\/privacy\/privacy-law-reform\/canadians-care-about-privacy-politicians-need-to-show-they-care-about-us\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ccla.org\/"},{"@type":"ListItem","position":2,"name":"PRIVACY","item":"https:\/\/ccla.org\/category\/privacy\/"},{"@type":"ListItem","position":3,"name":"Privacy Law Reform","item":"https:\/\/ccla.org\/fr\/category\/privacy\/privacy-law-reform\/"},{"@type":"ListItem","position":4,"name":"Canadians Care about Privacy, Politicians Need to Show They Care About Us"}]},{"@type":"WebSite","@id":"https:\/\/ccla.org\/#website","url":"https:\/\/ccla.org\/","name":"CCLA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccla.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/ccla.org\/#\/schema\/person\/c0ab72c13438e404cfca5f071db582f8","name":"Brenda McPhail","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/b88e2b9b83f05dd6b511990cc78ba746?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b88e2b9b83f05dd6b511990cc78ba746?s=96&d=blank&r=g","caption":"Brenda McPhail"},"sameAs":["https:\/\/x.com\/Brenda"],"url":"https:\/\/ccla.org\/fr\/author\/brenda\/"}]}},"_links":{"self":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/2542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/comments?post=2542"}],"version-history":[{"count":3,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/2542\/revisions"}],"predecessor-version":[{"id":6521,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/2542\/revisions\/6521"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media\/1120"}],"wp:attachment":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media?parent=2542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/categories?post=2542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/tags?post=2542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}