{"id":1964,"date":"2020-08-27T09:01:24","date_gmt":"2020-08-27T09:01:24","guid":{"rendered":"https:\/\/ccla.org\/?p=1964"},"modified":"2021-06-16T18:42:39","modified_gmt":"2021-06-16T18:42:39","slug":"statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta","status":"publish","type":"post","link":"https:\/\/ccla.org\/fr\/libertes-fondamentales\/droits-democratiques\/declaration-au-comite-special-dexamen-de-la-loi-sur-la-sante-publique-assemblee-legislative-de-lalberta\/","title":{"rendered":"D\u00e9claration au comit\u00e9 sp\u00e9cial d&#039;examen de la Loi sur la sant\u00e9 publique, Assembl\u00e9e l\u00e9gislative de l&#039;Alberta"},"content":{"rendered":"<div id=\"fws_6a043d604c81e\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a043d604cc0d\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: rgba(0,0,0,0.3); background: linear-gradient(to bottom,rgba(0,0,0,0.3) 0%,rgba(238,238,238,0.01) 100%);  opacity: 0.5; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a043d604ced1\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"4%\" data-bottom-percent=\"4%\"  class=\"wpb_row vc_row-fluid vc_row full-width-section post-links\"  style=\"padding-top: calc(100vw * 0.04); padding-bottom: calc(100vw * 0.04); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p><b>27 ao\u00fbt 2020<\/b> <em>V\u00e9rifier contre livraison<\/em> <span class=\"TextRun SCXW83627703 BCX0\" lang=\"EN-US\" xml:lang=\"EN-US\" data-contrast=\"auto\"><span class=\"NormalTextRun SCXW83627703 BCX0\">Fond\u00e9e en 1964, l&#039;ACLC est une organisation nationale, ind\u00e9pendante, \u00e0 but non lucratif et non gouvernementale vou\u00e9e \u00e0 la promotion des droits humains fondamentaux, des libert\u00e9s civiles, de la primaut\u00e9 du droit et de la responsabilit\u00e9 gouvernementale. Ses membres nationaux comprennent des milliers de sympathisants r\u00e9mun\u00e9r\u00e9s issus de tous les horizons. L&#039;objectif sous-jacent de son travail est de maintenir une soci\u00e9t\u00e9 libre et d\u00e9mocratique au Canada qui \u00e9quilibre les libert\u00e9s civiles et les int\u00e9r\u00eats publics et priv\u00e9s concurrents.\u00a0<\/span><\/span> <span data-contrast=\"auto\">Le point cl\u00e9\u00a0<\/span><span data-contrast=\"auto\">L&#039;ACLC souhaite\u00a0<\/span><span data-contrast=\"auto\">apporter aux changements que le projet de loi 10 a promulgu\u00e9s est qu&#039;ils ne \u00ab clarifient \u00bb pas simplement (comme le gouvernement a essay\u00e9 de le faire valoir) les pouvoirs dont disposent les ministres en cas d&#039;urgence - ils \u00e9tendent ces pouvoirs afin que le ministre puisse ajouter de nouvelles dispositions \u00e0 une loi qui ne ne modifiez pas simplement une disposition existante.\u00a0<\/span><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">Cabinet des ministres<\/span><span data-contrast=\"auto\">\u00a0peut cr\u00e9er de nouveaux pouvoirs juridiques qui limitent les libert\u00e9s individuelles et les libert\u00e9s<\/span><span data-contrast=\"auto\">.\u00a0\u00a0<\/span><span data-contrast=\"auto\">Cela conf\u00e8re \u00e0 une seule personne trop de pouvoir qui peut faire trop de mal \u00e0 nos droits. Cette\u00a0<\/span><span data-contrast=\"auto\">D\u00e9passement minist\u00e9riel<\/span><span data-contrast=\"auto\">\u00a0est exerc\u00e9<\/span><span data-contrast=\"auto\">,\u00a0<\/span><span data-contrast=\"auto\">par n\u00e9cessit\u00e9,\u00a0<\/span><span data-contrast=\"auto\">en secret, ou \u00e0 huis clos,\u00a0<\/span><span data-contrast=\"auto\">sans contr\u00f4le l\u00e9gislatif.\u00a0\u00a0<\/span><span data-contrast=\"auto\">l&#039;ACLC<\/span><span data-contrast=\"auto\">\u00a0l&#039;inqui\u00e9tude est que cela contourne le processus l\u00e9gislatif et, bien qu&#039;il soit temporaire,\u00a0<\/span><span data-contrast=\"auto\">c&#039;est \u00e0 la fois inconstitutionnel et pr\u00e9judiciable \u00e0 vos \u00e9lecteurs.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">En quoi est-ce nocif pour vos \u00e9lecteurs?\u00a0\u00a0<\/span><span data-contrast=\"auto\">Pourquoi tout cela est-il important ? Parce que\u00a0<\/span><span data-contrast=\"auto\">vos \u00e9lecteurs sont<\/span><span data-contrast=\"auto\">\u00a0libre d&#039;aller\u00a0<\/span><span data-contrast=\"auto\">leur<\/span><span data-contrast=\"auto\">\u00a0Entreprise<\/span><span data-contrast=\"auto\">\u00a0comme ils l&#039;entendent, sous r\u00e9serve des limites constitutionnelles et l\u00e9gales<\/span><span data-contrast=\"auto\">. Un homme ne peut pas se pr\u00e9senter et m&#039;enfermer ou me d\u00e9tenir ou m&#039;emprisonner ou mes enfants. Un policier ne peut pas non plus faire cela, sauf dans la mesure o\u00f9 il est autoris\u00e9 par la loi \u00e0 toucher \u00e0 ma libert\u00e9. Cette loi autorisant l&#039;ing\u00e9rence dans ma libert\u00e9, cette loi doit \u00eatre une loi constitutionnelle, adopt\u00e9e par la l\u00e9gislature, r\u00e9visable par les tribunaux. Si cette \u00e9tape d\u00e9mocratique et constitutionnelle est saut\u00e9e, il y a une plus grande possibilit\u00e9 d&#039;erreur,\u00a0<\/span><span data-contrast=\"auto\">plus de risques de dommages,\u00a0<\/span><span data-contrast=\"auto\">et aucune possibilit\u00e9 de responsabilisation. Si cette \u00e9tape est ignor\u00e9e, alors le ministre obtient peut-\u00eatre l&#039;ordonnance non pas lors d&#039;une r\u00e9union pl\u00e9ni\u00e8re du Cabinet, mais au moyen d&#039;une visite guid\u00e9e, de sorte que le procureur g\u00e9n\u00e9ral n&#039;ait aucune chance de donner son avis sur son statut constitutionnel.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">Du point de vue de la sant\u00e9 publique, il existe un risque scientifique qui survient lorsqu&#039;une ordonnance de sant\u00e9 publique est prise sans processus d\u00e9mocratique. En 2005, l&#039;\u00e9pid\u00e9miologiste John Ioannidis de l&#039;Universit\u00e9 de Stanford en Californie a sugg\u00e9r\u00e9 que la plupart des r\u00e9sultats publi\u00e9s \u00e9taient faux ; depuis lors, une s\u00e9rie de probl\u00e8mes de r\u00e9plication tr\u00e8s m\u00e9diatis\u00e9s a oblig\u00e9 les scientifiques \u00e0 repenser la fa\u00e7on dont ils \u00e9valuent les r\u00e9sultats. Pendant ce temps, les statisticiens recherchent de meilleures fa\u00e7ons de penser aux donn\u00e9es, pour aider les scientifiques \u00e0 \u00e9viter de manquer des informations importantes ou d&#039;agir sur de fausses alarmes. Comme le dit Steven Goodman, m\u00e9decin et statisticien \u00e0 Stanford : \u00ab\u00a0Changez votre philosophie statistique et tout \u00e0 coup, des choses diff\u00e9rentes deviennent importantes.\u00a0\u00bb\u00a0\u00a0<\/span><span data-contrast=\"auto\">Mon point \u00e9tant que la science est en constante \u00e9volution.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">Lorsqu&#039;un nouveau pouvoir de sant\u00e9 publique est cr\u00e9\u00e9 et soumis \u00e0 la l\u00e9gislature, les membres de l&#039;opposition et les journalistes ont la possibilit\u00e9 de trouver des professionnels de la sant\u00e9 publique pour commenter ou s&#039;opposer au projet de loi sur la sant\u00e9 publique. Un d\u00e9bat est autoris\u00e9. Il se peut que le m\u00e9decin-chef r\u00e9v\u00e8le lors d&#039;une m\u00eal\u00e9e m\u00e9diatique que ce nouveau pouvoir manquait de n\u00e9cessit\u00e9 m\u00e9dicale ou de proportionnalit\u00e9. Nous pouvons d\u00e9couvrir que c&#039;est juste quelque chose qu&#039;un syndicat de police voulait, ou quelque chose qu&#039;un\u00a0<\/span><span data-contrast=\"auto\">politicien<\/span><span data-contrast=\"auto\">\u00a0cr\u00e9\u00e9 pour des raisons<\/span><span data-contrast=\"auto\">\u00a0rien \u00e0 voir avec la sant\u00e9 publique<\/span><span data-contrast=\"auto\">, ou \u00e9tait fond\u00e9e sur le caprice d&#039;un ministre ou d&#039;un premier ministre.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">Mais si la nouvelle loi sur la sant\u00e9 publique est cr\u00e9\u00e9e par d\u00e9cret du Cabinet, ce qui est n\u00e9cessairement secret, \u00e0 huis clos, alors c&#039;est fait, et la solidarit\u00e9 du Cabinet am\u00e8ne le gouvernement \u00e0 encercler les wagons et \u00e0 le d\u00e9fendre \u00e0 tout prix, car renverser cette d\u00e9cision est politiquement trop co\u00fbteux.\u00a0\u00a0<\/span><span data-contrast=\"auto\">C&#039;est toi<\/span><span data-contrast=\"auto\">comme un<\/span><span data-contrast=\"auto\">\u00a0facture\u00a0<\/span><span data-contrast=\"auto\">amendement, qui est rarement une calamit\u00e9 politique, et appara\u00eet comme une d\u00e9mocratie en action. Plus important encore, la disposition l\u00e9gislative modifi\u00e9e \u00e0 l&#039;\u00e9tude article par article ou autrement en comit\u00e9 n&#039;a pas port\u00e9 atteinte aux droits et libert\u00e9s des peuples. La vie priv\u00e9e ou la libert\u00e9 de personne n&#039;a \u00e9t\u00e9 vol\u00e9e\u00a0<\/span><span data-contrast=\"auto\">si une disposition de facture\u00a0<\/span><span data-contrast=\"auto\">est chang\u00e9<\/span><span data-contrast=\"auto\">\u00a0lors du d\u00e9bat sur ce projet de loi<\/span><span data-contrast=\"auto\">. L&#039;arr\u00eat\u00e9 minist\u00e9riel, en revanche, commence \u00e0 faire du tort parfois avant m\u00eame que le public ne sache qu&#039;il a \u00e9t\u00e9 mis en vigueur.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">La transparence sur les nouveaux arr\u00eat\u00e9s et r\u00e8glements minist\u00e9riels est enti\u00e8rement ouverte \u00e0 la manipulation<\/span><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">\u2013 cela requiert une attention particuli\u00e8re des Comit\u00e9s.\u00a0\u00a0<\/span><span data-contrast=\"auto\">L&#039;ACLC demande au<\/span><span data-contrast=\"auto\">\u00a0Le Comit\u00e9 recommande qu&#039;une exigence pour toutes les ordonnances en vertu de la Loi soit rendue publique, dans son int\u00e9gralit\u00e9, d&#039;une mani\u00e8re imm\u00e9diatement accessible\u00a0<\/span><span data-contrast=\"auto\">dans un endroit centralis\u00e9<\/span><span data-contrast=\"auto\">\u00a0en ligne qui est tweet\u00e9 par le gouvernement,\u00a0<\/span><span data-contrast=\"auto\">au moment o\u00f9 ils sont\u00a0<\/span><span data-contrast=\"auto\">r\u00e9alis\u00e9<\/span><span data-contrast=\"auto\">. Actuellement, en vertu de l&#039;article 52.4, le\u00a0<\/span><span data-contrast=\"auto\">l&#039;exigence est beaucoup trop l\u00e2che, il dit que le gouvernement<\/span><span data-contrast=\"auto\">\u00a0\u00ab\u00a0publie et met \u00e0 disposition les d\u00e9tails d&#039;une commande\u2026 de la mani\u00e8re que la personne juge appropri\u00e9e\u00a0\u00bb.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">Ces clauses Henri VIII\u00a0<\/span><span data-contrast=\"auto\">offenser la s\u00e9paration constitutionnelle des pouvoirs entre les branches l\u00e9gislatives et ex\u00e9cutives du gouvernement qui sont fondamentales dans le Commonwealth et ailleurs (y compris les \u00c9tats-Unis et l&#039;Irlande).\u00a0<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">Le fait que ce risque soit r\u00e9el, et non th\u00e9orique, ressort clairement du fait que le ministre de la Sant\u00e9 s&#039;est appuy\u00e9 sur les modifications pour \u00e9mettre l&#039;arr\u00eat\u00e9 minist\u00e9riel 632\/2020, accordant au m\u00e9decin-chef le pouvoir de divulguer les dossiers de sant\u00e9 de personnes individuelles aux services de police pour permettre aux policiers de d\u00e9terminer s&#039;ils ont \u00e9t\u00e9 en contact \u00e9troit avec une personne test\u00e9e positive pour COVID-19.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">L&#039;exemple donn\u00e9, de quelqu&#039;un crachant sur un policier \u2013 y a-t-il eu une \u00e9pid\u00e9mie de personnes crachant sur la police, justifiant cette nouvelle loi ? \u00c9tait-ce une hypoth\u00e8se ou une anomalie ?\u00a0\u00a0<\/span><span data-contrast=\"auto\">C&#039;est-\u00e0-dire, a-t-il satisfait au crit\u00e8re de n\u00e9cessit\u00e9.\u00a0\u00a0<\/span><span data-contrast=\"auto\">Y avait-il des preuves ou des donn\u00e9es scientifiques derri\u00e8re cette\u00a0<\/span><span data-contrast=\"auto\">Commander?\u00a0\u00a0<\/span><span data-contrast=\"auto\">Plus important encore, les lois actuelles pourraient-elles\u00a0<\/span><span data-contrast=\"auto\">ont\u00a0<\/span><span data-contrast=\"auto\">fait le tour ?\u00a0\u00a0<\/span><span data-contrast=\"auto\">Les deux parties n&#039;auraient-elles pas besoin d&#039;\u00eatre test\u00e9es de toute fa\u00e7on, \u00e0 l&#039;aide d&#039;un mandat, en vertu des lois existantes\u00a0? Si non, pourquoi pas ? C&#039;est-\u00e0-dire, a-t-il satisfait au crit\u00e8re de proportionnalit\u00e9.<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">Maintenant, les arguments constitutionnels peuvent en effet \u00eatre pr\u00e9sent\u00e9s au pouvoir judiciaire, et vous pouvez vous demander pourquoi un d\u00e9put\u00e9 ou le grand public serait concern\u00e9 par\u00a0<\/span><span data-contrast=\"auto\">quelque chose d&#039;aussi obscur que la s\u00e9paration l\u00e9gale des pouvoirs. Est-ce juste une technicit\u00e9 formaliste ?\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">Non.\u00a0\u00a0<\/span><span data-contrast=\"auto\">Clauses Henri VIII<\/span><span data-contrast=\"auto\">\u00a0vraiment\u00a0<\/span><span data-contrast=\"auto\">interf\u00e9rer avec notre d\u00e9mocratie, vos emplois et les op\u00e9rations de l&#039;Assembl\u00e9e l\u00e9gislative. En un mot, il est important pour des raisons de\u00a0<\/span><span data-contrast=\"auto\">responsabilit\u00e9.\u00a0<\/span><span data-contrast=\"auto\">\u00a0Sur un projet de loi devant l&#039;Assembl\u00e9e, y<\/span><span data-contrast=\"auto\">Vous devez voter oui ou non, et cela constitue un dossier auquel vous \u00eates tous tenus de\u00a0<\/span><span data-contrast=\"auto\">compte aux prochaines \u00e9lections. Mais cette responsabilit\u00e9 d\u00e9mocratique est impossible si un nouveau pouvoir juridique est cr\u00e9\u00e9 \u00e0 huis clos par un Cabinet\u00a0<\/span><span data-contrast=\"auto\">Ministre<\/span><span data-contrast=\"auto\">.\u00a0\u00a0<\/span><span data-ccp-props=\"{&quot;335559738&quot;:240}\">\u00a0<\/span> <span data-contrast=\"auto\">Exiger\u00a0<\/span><span data-contrast=\"auto\">que les nouveaux pouvoirs juridiques ne soient autoris\u00e9s que par le l\u00e9gislateur a une importance pratique, d\u00e9mocratique,\u00a0<\/span><span data-contrast=\"auto\">int\u00e9r\u00eat public<\/span><span data-contrast=\"auto\">\u00a0<\/span><span data-contrast=\"auto\">fonction. Les affaires de votre assembl\u00e9e l\u00e9gislative\u00a0<\/span><span data-contrast=\"auto\">peut ne pas \u00eatre surveill\u00e9 de pr\u00e8s par une majorit\u00e9 de\u00a0<\/span><span data-contrast=\"auto\">vos \u00e9lecteurs<\/span><span data-contrast=\"auto\">. Mais cette affaire, ce d\u00e9bat l\u00e9gislatif, chaque jour qu&#039;il a lieu, attire l&#039;attention des tribunes de la presse provinciale et parfois nationale.\u00a0\u00a0<\/span><span data-contrast=\"auto\">Il peut cr\u00e9er une dynamique, je dirais une dynamique d\u00e9mocratique, qui permet\u00a0<\/span><span data-contrast=\"auto\">un consensus public \u00e0 d\u00e9velopper,<\/span><span data-contrast=\"auto\">\u00a0\u00e0 travers l&#039;actualit\u00e9 quotidienne<\/span><span data-contrast=\"auto\">\u00a0et diffusions horaires et m\u00e9dias sociaux. La p\u00e9riode des questions peut devenir domin\u00e9e par le sujet de la loi.\u00a0\u00a0<\/span><span data-contrast=\"auto\">C&#039;est ce qui s&#039;est pass\u00e9,\u00a0<\/span><span data-contrast=\"auto\">il y a deux mois<\/span><span data-contrast=\"auto\">, lorsque\u00a0<\/span><span data-contrast=\"auto\">le premier ministre du Nouveau-Brunswick a annonc\u00e9 que son gouvernement abandonnerait\u00a0<\/span><span data-contrast=\"auto\">son\u00a0<\/span><span data-contrast=\"auto\">Projet de loi 49\u00a0<\/span><span data-contrast=\"auto\">du Feuilleton, apr\u00e8s le toll\u00e9 g\u00e9n\u00e9ral contre les lois exag\u00e9r\u00e9es\u00a0<\/span><span data-contrast=\"auto\">des pouvoirs d&#039;urgence<\/span><span data-contrast=\"auto\">.\u00a0\u00a0<\/span><span data-contrast=\"auto\">Il s&#039;agit d&#039;un exemple de<\/span><span data-contrast=\"auto\">\u00a0gouvernement\u00a0<\/span><span data-contrast=\"auto\">prot\u00e9ger\u00a0<\/span><span data-contrast=\"auto\">lui-m\u00eame<\/span><span data-contrast=\"auto\">\u00a0de ses pires instincts<\/span><span data-contrast=\"auto\">,\u00a0<\/span><span data-contrast=\"auto\">mais plus important\u00a0<\/span><span data-contrast=\"auto\">prot\u00e8ge les libert\u00e9s des peuples et prot\u00e8ge\u00a0<\/span><span data-contrast=\"auto\">vous, d\u00e9put\u00e9s du gouvernement, d&#039;\u00eatre tenus responsables\u00a0<\/span><span data-contrast=\"auto\">par vos \u00e9lecteurs\u00a0<\/span><span data-contrast=\"auto\">pour quelque chose\u00a0<\/span><span data-contrast=\"auto\">vous n&#039;avez m\u00eame jamais vot\u00e9 pour.<\/span><span data-contrast=\"auto\">\u00a0\u00a0<\/span><span data-contrast=\"auto\">Pour les d\u00e9put\u00e9s de l&#039;opposition, vous n&#039;avez jamais la possibilit\u00e9 de ralentir le gouvernement ou de d\u00e9clarer publiquement que vous vous opposez \u00e0 l&#039;action du gouvernement.<\/span><span data-contrast=\"auto\">n, si le nouveau pouvoir l\u00e9gal n&#039;est jamais all\u00e9 devant votre Assembl\u00e9e.<\/span><\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a043d604d4f1\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a043d604d8c4\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"1%\" data-bottom-percent=\"1%\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: calc(100vw * 0.01); padding-bottom: calc(100vw * 0.01); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >\u00c0 propos de l\u2019association canadienne sur les libert\u00e9s civiles<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p class=\"translation-block\">L\u2019ACLC est un organisme ind\u00e9pendant \u00e0 but non lucratif qui compte des sympathisant.e.s dans tout le pays. Fond\u00e9 en 1964, c\u2019est un organisme qui \u0153uvre \u00e0 l\u2019\u00e9chelle du Canada \u00e0 la protection des droits et des libert\u00e9s civiles de toute sa population.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les m\u00e9dias<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Pour d&#039;autres commentaires, veuillez nous contacter \u00e0\u00a0<a href=\"mailto:media@ccla.org\"><u>media@ccla.org<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les mises \u00e0 jour en direct<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Veuillez continuer \u00e0 vous r\u00e9f\u00e9rer \u00e0\u00a0<a href=\"https:\/\/ccla.org\/fr\/the-latest\/\" rel=\"noopener\">cette page<\/a>\u00a0et \u00e0 nos plateformes de m\u00e9dias sociaux. On est dessus\u00a0<a href=\"https:\/\/www.instagram.com\/cancivlib\/?hl=en\" target=\"_blank\" rel=\"noopener\"><u>Instagram<\/u><\/a>,\u00a0<a href=\"http:\/\/facebook.com\/cancivlib\/\" target=\"_blank\" rel=\"noopener\"><u>Facebook<\/u><\/a>, <a href=\"https:\/\/twitter.com\/cancivlib\" target=\"_blank\" rel=\"noopener\"><u>Twitter<\/u><\/a> et <a href=\"https:\/\/bsky.app\/profile\/cancivlib.bsky.social\" target=\"_blank\" rel=\"noopener\"><u>Ciel bleu<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>Fond\u00e9e en 1964, l&#039;ACLC est une organisation nationale, ind\u00e9pendante, \u00e0 but non lucratif et non gouvernementale vou\u00e9e \u00e0 la promotion des droits humains fondamentaux, des libert\u00e9s civiles, de la primaut\u00e9 du droit et de la responsabilit\u00e9 gouvernementale. Ses membres nationaux comprennent des milliers de sympathisants r\u00e9mun\u00e9r\u00e9s issus de tous les horizons. L&#039;objectif sous-jacent de son travail est de maintenir une soci\u00e9t\u00e9 libre et d\u00e9mocratique au Canada qui \u00e9quilibre les libert\u00e9s civiles et les int\u00e9r\u00eats publics et priv\u00e9s concurrents. <\/p>","protected":false},"author":13,"featured_media":3648,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[27,79,31],"tags":[],"class_list":{"0":"post-1964","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-covid-19","8":"category-democratic-rights","9":"category-fundamental-freedoms"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Statement to Select Special Public Health Act Review Committee, Legislative Assembly of Alberta - CCLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccla.org\/fr\/libertes-fondamentales\/droits-democratiques\/declaration-au-comite-special-dexamen-de-la-loi-sur-la-sante-publique-assemblee-legislative-de-lalberta\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Statement to Select Special Public Health Act Review Committee, Legislative Assembly of Alberta - CCLA\" \/>\n<meta property=\"og:description\" content=\"Founded in 1964, the CCLA is a national, independent, non-profit, non-governmental organization dedicated to furthering fundamental human rights, civil liberties, the rule of law and government accountability. Its national membership includes thousands of paid supporters drawn from all walks of life. The underlying purpose of its work is to maintain a free and democratic society in Canada that balances civil liberties and competing public and private interests.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccla.org\/fr\/libertes-fondamentales\/droits-democratiques\/declaration-au-comite-special-dexamen-de-la-loi-sur-la-sante-publique-assemblee-legislative-de-lalberta\/\" \/>\n<meta property=\"og:site_name\" content=\"CCLA\" \/>\n<meta property=\"article:published_time\" content=\"2020-08-27T09:01:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-16T18:42:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/AlbertaLegislatureBldg.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Michael Bryant\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MichaelLowry\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michael Bryant\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/\",\"url\":\"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/\",\"name\":\"Statement to Select Special Public Health Act Review Committee, Legislative Assembly of Alberta - CCLA\",\"isPartOf\":{\"@id\":\"https:\/\/ccla.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/AlbertaLegislatureBldg.jpg\",\"datePublished\":\"2020-08-27T09:01:24+00:00\",\"dateModified\":\"2021-06-16T18:42:39+00:00\",\"author\":{\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/4d193c844c2f67380377397c02ba56ea\"},\"breadcrumb\":{\"@id\":\"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#primaryimage\",\"url\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/AlbertaLegislatureBldg.jpg\",\"contentUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/AlbertaLegislatureBldg.jpg\",\"width\":2000,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ccla.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FUNDAMENTAL FREEDOMS\",\"item\":\"https:\/\/ccla.org\/category\/fundamental-freedoms\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Democratic Rights\",\"item\":\"https:\/\/ccla.org\/category\/fundamental-freedoms\/democratic-rights\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Statement to Select Special Public Health Act Review Committee, Legislative Assembly of Alberta\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ccla.org\/#website\",\"url\":\"https:\/\/ccla.org\/\",\"name\":\"CCLA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ccla.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/4d193c844c2f67380377397c02ba56ea\",\"name\":\"Michael Bryant\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/c7c3f9ad6e09b56f43bd52746ee8e385?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/c7c3f9ad6e09b56f43bd52746ee8e385?s=96&d=blank&r=g\",\"caption\":\"Michael Bryant\"},\"sameAs\":[\"https:\/\/x.com\/MichaelLowry\"],\"url\":\"https:\/\/ccla.org\/fr\/author\/michael\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Statement to Select Special Public Health Act Review Committee, Legislative Assembly of Alberta - CCLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccla.org\/fr\/libertes-fondamentales\/droits-democratiques\/declaration-au-comite-special-dexamen-de-la-loi-sur-la-sante-publique-assemblee-legislative-de-lalberta\/","og_locale":"fr_CA","og_type":"article","og_title":"Statement to Select Special Public Health Act Review Committee, Legislative Assembly of Alberta - CCLA","og_description":"Founded in 1964, the CCLA is a national, independent, non-profit, non-governmental organization dedicated to furthering fundamental human rights, civil liberties, the rule of law and government accountability. Its national membership includes thousands of paid supporters drawn from all walks of life. The underlying purpose of its work is to maintain a free and democratic society in Canada that balances civil liberties and competing public and private interests.","og_url":"https:\/\/ccla.org\/fr\/libertes-fondamentales\/droits-democratiques\/declaration-au-comite-special-dexamen-de-la-loi-sur-la-sante-publique-assemblee-legislative-de-lalberta\/","og_site_name":"CCLA","article_published_time":"2020-08-27T09:01:24+00:00","article_modified_time":"2021-06-16T18:42:39+00:00","og_image":[{"width":2000,"height":800,"url":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/AlbertaLegislatureBldg.jpg","type":"image\/jpeg"}],"author":"Michael Bryant","twitter_card":"summary_large_image","twitter_creator":"@MichaelLowry","twitter_misc":{"\u00c9crit par":"Michael Bryant","Estimation du temps de lecture":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/","url":"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/","name":"Statement to Select Special Public Health Act Review Committee, Legislative Assembly of Alberta - CCLA","isPartOf":{"@id":"https:\/\/ccla.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#primaryimage"},"image":{"@id":"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#primaryimage"},"thumbnailUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/AlbertaLegislatureBldg.jpg","datePublished":"2020-08-27T09:01:24+00:00","dateModified":"2021-06-16T18:42:39+00:00","author":{"@id":"https:\/\/ccla.org\/#\/schema\/person\/4d193c844c2f67380377397c02ba56ea"},"breadcrumb":{"@id":"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#primaryimage","url":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/AlbertaLegislatureBldg.jpg","contentUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/AlbertaLegislatureBldg.jpg","width":2000,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/ccla.org\/fundamental-freedoms\/democratic-rights\/statement-to-select-special-public-health-act-review-committee-legislative-assembly-of-alberta\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ccla.org\/"},{"@type":"ListItem","position":2,"name":"FUNDAMENTAL FREEDOMS","item":"https:\/\/ccla.org\/category\/fundamental-freedoms\/"},{"@type":"ListItem","position":3,"name":"Democratic Rights","item":"https:\/\/ccla.org\/category\/fundamental-freedoms\/democratic-rights\/"},{"@type":"ListItem","position":4,"name":"Statement to Select Special Public Health Act Review Committee, Legislative Assembly of Alberta"}]},{"@type":"WebSite","@id":"https:\/\/ccla.org\/#website","url":"https:\/\/ccla.org\/","name":"CCLA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccla.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/ccla.org\/#\/schema\/person\/4d193c844c2f67380377397c02ba56ea","name":"Michael Bryant","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/c7c3f9ad6e09b56f43bd52746ee8e385?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/c7c3f9ad6e09b56f43bd52746ee8e385?s=96&d=blank&r=g","caption":"Michael Bryant"},"sameAs":["https:\/\/x.com\/MichaelLowry"],"url":"https:\/\/ccla.org\/fr\/author\/michael\/"}]}},"_links":{"self":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/1964","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/comments?post=1964"}],"version-history":[{"count":2,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/1964\/revisions"}],"predecessor-version":[{"id":4003,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/1964\/revisions\/4003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media\/3648"}],"wp:attachment":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media?parent=1964"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/categories?post=1964"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/tags?post=1964"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}