{"id":11980,"date":"2026-04-02T16:56:04","date_gmt":"2026-04-02T20:56:04","guid":{"rendered":"https:\/\/ccla.org\/?p=11980"},"modified":"2026-04-02T16:56:04","modified_gmt":"2026-04-02T20:56:04","slug":"ccla-strongly-condemns-passage-of-quebecs-bill-9","status":"publish","type":"post","link":"https:\/\/ccla.org\/fr\/communique-de-presse\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/","title":{"rendered":"L'ACLC condamne fermement l'adoption du projet de loi 9 au Qu\u00e9bec"},"content":{"rendered":"<div id=\"fws_6a04285f64307\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a04285f64792\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: rgba(0,0,0,0.3); background: linear-gradient(to bottom,rgba(0,0,0,0.3) 0%,rgba(238,238,238,0.01) 100%);  opacity: 0.5; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04285f64a7c\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>MONTR\u00c9AL \u2014 L\u2019Association canadienne des libert\u00e9s civiles (ACLC) condamne fermement l\u2019adoption du projet de loi 9 du Qu\u00e9bec.<\/p>\n<p>L\u2019adoption du projet de loi 9 est un autre exemple de l\u2019attaque incessante du gouvernement du Qu\u00e9bec sur la libert\u00e9 de religion, la libert\u00e9 d\u2019expression, les droits de protestation et l\u2019\u00e9galit\u00e9. En invoquant une nouvelle fois les dispositions de d\u00e9rogation des chartes des droits et libert\u00e9s du Qu\u00e9bec et du Canada, le gouvernement du Qu\u00e9bec a \u00e9largi son utilisation des pouvoirs l\u00e9gislatifs extraordinaires pour passer outre aux droits et aux libert\u00e9s fondamentaux, cr\u00e9ant ainsi un dangereux pr\u00e9c\u00e9dent pour l\u2019\u00e9rosion des protections constitutionnelles pour les Qu\u00e9b\u00e9cois.<\/p>\n<p>Le projet de loi 9 aggrave les pr\u00e9judices caus\u00e9s par le projet de loi 21 en \u00e9tendant l\u2019interdiction du port de symboles religieux actuellement en vigueur au personnel des garderies et des \u00e9tablissements d\u2019enseignement priv\u00e9s subventionn\u00e9s. Il interdit \u00e9galement le port de voiles religieux couvrant le visage aux personnes qui re\u00e7oivent des services \u00e9ducatifs et restreint les accommodements religieux dans le secteur public. Ces mesures pr\u00e9judiciables ciblent et marginalisent de mani\u00e8re disproportionn\u00e9e les minorit\u00e9s religieuses et racis\u00e9es, en particulier les femmes musulmanes.<\/p>\n<p>\u00ab\u2009Il est particuli\u00e8rement inqui\u00e9tant que l\u2019Assembl\u00e9e nationale du Qu\u00e9bec ait adopt\u00e9 cette loi qui \u00e9largit la port\u00e9e des pr\u00e9judices caus\u00e9s par le projet de loi 21 pendant que la Cour supr\u00eame du Canada d\u00e9termine la validit\u00e9 constitutionnelle du projet de loi 21\u2009\u00bb, a d\u00e9clar\u00e9 Harini Sivalingam, directrice du programme \u00c9galit\u00e9 de l\u2019ACLC.<\/p>\n<p>Le projet de loi 9 repr\u00e9sente une atteinte manifeste et inqui\u00e9tante \u00e0 la libert\u00e9 de religion, d\u2019expression et de r\u00e9union pacifique. Cette loi de grande port\u00e9e instaure de graves limites \u00e0 la pratique religieuse collective en public et cr\u00e9e de nouvelles restrictions susceptibles de p\u00e9naliser les manifestations pacifiques \u00e0 proximit\u00e9 des lieux de culte.<\/p>\n<p>\u00ab Les espaces publics appartiennent \u00e0 tout le monde. Le droit de manifester pacifiquement et d\u2019exprimer publiquement ses croyances religieuses ne doit pas \u00eatre restreint sous le pr\u00e9texte de la neutralit\u00e9 de l\u2019\u00c9tat, a affirm\u00e9 Ana\u00efs Bussi\u00e8res McNicoll, directrice du programme des libert\u00e9s fondamentales de l\u2019ACLC. La la\u00efcit\u00e9 de l\u2019\u00c9tat n\u2019autorise pas \u00e0 porter atteindre aux droits et aux libert\u00e9s fondamentaux qui sont essentiels dans une soci\u00e9t\u00e9 d\u00e9mocratique. \u00bb<\/p>\n<p>L\u2019ACLC avertit que la normalisation de l\u2019utilisation du droit constitutionnel de d\u00e9rogation pour adopter des lois portant atteinte aux libert\u00e9s fondamentales risque d\u2019affaiblir les protections des droits pour tout le monde. Les gouvernements ne devraient pas \u00eatre autoris\u00e9s \u00e0 contourner les protections pr\u00e9vues par la Charte chaque fois que des droits deviennent politiquement g\u00eanants.<\/p>\n<p>\u00ab\u2009Les droits et les libert\u00e9s ne sont pas facultatifs et ne devraient pas d\u00e9pendre du gouvernement du jour, a affirm\u00e9 Howard Sapers, directeur g\u00e9n\u00e9ral de l\u2019ACLC. Quand les gouvernements adoptent des lois qui ciblent les minorit\u00e9s et limitent les libert\u00e9s fondamentales, ils minent les droits de tout le monde.\u2009\u00bb<\/p>\n<p>L\u2019ACLC est solidaire des communaut\u00e9s les plus directement touch\u00e9es par cette loi et continuera de d\u00e9fendre les droits et les libert\u00e9s fondamentaux de tous les gens du Qu\u00e9bec et de partout au Canada.<\/p>\n<p class=\"translation-block\">Lisez le m\u00e9moire de l ACLC \u00e0 l\u2019Assembl\u00e9e nationale  <a href=\"https:\/\/ccla.org\/wp-content\/uploads\/2026\/02\/2026-02-09-Memoire-de-lACLC.pdf\" target=\"_self\">ici<\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a04285f64d3d\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a04285f65028\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"1%\" data-bottom-percent=\"1%\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: calc(100vw * 0.01); padding-bottom: calc(100vw * 0.01); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >\u00c0 propos de l\u2019association canadienne sur les libert\u00e9s civiles<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p class=\"translation-block\">L\u2019ACLC est un organisme ind\u00e9pendant \u00e0 but non lucratif qui compte des sympathisant.e.s dans tout le pays. Fond\u00e9 en 1964, c\u2019est un organisme qui \u0153uvre \u00e0 l\u2019\u00e9chelle du Canada \u00e0 la protection des droits et des libert\u00e9s civiles de toute sa population.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les m\u00e9dias<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Pour d&#039;autres commentaires, veuillez nous contacter \u00e0\u00a0<a href=\"mailto:media@ccla.org\"><u>media@ccla.org<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les mises \u00e0 jour en direct<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Veuillez continuer \u00e0 vous r\u00e9f\u00e9rer \u00e0\u00a0<a href=\"https:\/\/ccla.org\/fr\/the-latest\/\" rel=\"noopener\">cette page<\/a>\u00a0et \u00e0 nos plateformes de m\u00e9dias sociaux. On est dessus\u00a0<a href=\"https:\/\/www.instagram.com\/cancivlib\/?hl=en\" target=\"_blank\" rel=\"noopener\"><u>Instagram<\/u><\/a>,\u00a0<a href=\"http:\/\/facebook.com\/cancivlib\/\" target=\"_blank\" rel=\"noopener\"><u>Facebook<\/u><\/a>, <a href=\"https:\/\/twitter.com\/cancivlib\" target=\"_blank\" rel=\"noopener\"><u>Twitter<\/u><\/a> et <a href=\"https:\/\/bsky.app\/profile\/cancivlib.bsky.social\" target=\"_blank\" rel=\"noopener\"><u>Ciel bleu<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"MONTR\u00c9AL - L'Association canadienne des libert\u00e9s civiles (ACLC) condamne fermement l'adoption du projet de loi 9 du Qu\u00e9bec. L'adoption du projet de loi 9 est un autre exemple de l'attaque continue du gouvernement du Qu\u00e9bec contre...","protected":false},"author":4,"featured_media":4504,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[66,252,6,8,44],"tags":[],"class_list":{"0":"post-11980","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-bill-21","8":"category-democratic-emergency-in-quebec","9":"category-equality","10":"category-press-release","11":"category-race-religion-ethnicity"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>CCLA Strongly Condemns Passage of Quebec\u2019s Bill 9 - CCLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccla.org\/fr\/communique-de-presse\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CCLA Strongly Condemns Passage of Quebec\u2019s Bill 9 - CCLA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccla.org\/fr\/communique-de-presse\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/\" \/>\n<meta property=\"og:site_name\" content=\"CCLA\" \/>\n<meta property=\"article:published_time\" content=\"2026-04-02T20:56:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/asia-muslim-lady-using-computer-laptop-talk-to-col-AGXC8AB-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"CCLA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CCLA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/\",\"url\":\"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/\",\"name\":\"CCLA Strongly Condemns Passage of Quebec\u2019s Bill 9 - CCLA\",\"isPartOf\":{\"@id\":\"https:\/\/ccla.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/asia-muslim-lady-using-computer-laptop-talk-to-col-AGXC8AB-1.jpg\",\"datePublished\":\"2026-04-02T20:56:04+00:00\",\"author\":{\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d\"},\"breadcrumb\":{\"@id\":\"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#primaryimage\",\"url\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/asia-muslim-lady-using-computer-laptop-talk-to-col-AGXC8AB-1.jpg\",\"contentUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/asia-muslim-lady-using-computer-laptop-talk-to-col-AGXC8AB-1.jpg\",\"width\":2000,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ccla.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRESS RELEASES\",\"item\":\"https:\/\/ccla.org\/category\/press-release\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"CCLA Strongly Condemns Passage of Quebec\u2019s Bill 9\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ccla.org\/#website\",\"url\":\"https:\/\/ccla.org\/\",\"name\":\"CCLA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ccla.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d\",\"name\":\"CCLA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g\",\"caption\":\"CCLA\"},\"url\":\"https:\/\/ccla.org\/fr\/author\/ccla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CCLA Strongly Condemns Passage of Quebec\u2019s Bill 9 - CCLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccla.org\/fr\/communique-de-presse\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/","og_locale":"fr_CA","og_type":"article","og_title":"CCLA Strongly Condemns Passage of Quebec\u2019s Bill 9 - CCLA","og_url":"https:\/\/ccla.org\/fr\/communique-de-presse\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/","og_site_name":"CCLA","article_published_time":"2026-04-02T20:56:04+00:00","og_image":[{"width":2000,"height":800,"url":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/asia-muslim-lady-using-computer-laptop-talk-to-col-AGXC8AB-1.jpg","type":"image\/jpeg"}],"author":"CCLA","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CCLA","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/","url":"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/","name":"CCLA Strongly Condemns Passage of Quebec\u2019s Bill 9 - CCLA","isPartOf":{"@id":"https:\/\/ccla.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#primaryimage"},"image":{"@id":"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#primaryimage"},"thumbnailUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/asia-muslim-lady-using-computer-laptop-talk-to-col-AGXC8AB-1.jpg","datePublished":"2026-04-02T20:56:04+00:00","author":{"@id":"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d"},"breadcrumb":{"@id":"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#primaryimage","url":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/asia-muslim-lady-using-computer-laptop-talk-to-col-AGXC8AB-1.jpg","contentUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2021\/06\/asia-muslim-lady-using-computer-laptop-talk-to-col-AGXC8AB-1.jpg","width":2000,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/ccla.org\/press-release\/ccla-strongly-condemns-passage-of-quebecs-bill-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ccla.org\/"},{"@type":"ListItem","position":2,"name":"PRESS RELEASES","item":"https:\/\/ccla.org\/category\/press-release\/"},{"@type":"ListItem","position":3,"name":"CCLA Strongly Condemns Passage of Quebec\u2019s Bill 9"}]},{"@type":"WebSite","@id":"https:\/\/ccla.org\/#website","url":"https:\/\/ccla.org\/","name":"CCLA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccla.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d","name":"CCLA","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g","caption":"CCLA"},"url":"https:\/\/ccla.org\/fr\/author\/ccla\/"}]}},"_links":{"self":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/11980","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/comments?post=11980"}],"version-history":[{"count":5,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/11980\/revisions"}],"predecessor-version":[{"id":11985,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/11980\/revisions\/11985"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media\/4504"}],"wp:attachment":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media?parent=11980"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/categories?post=11980"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/tags?post=11980"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}