{"id":11774,"date":"2026-03-12T12:12:57","date_gmt":"2026-03-12T16:12:57","guid":{"rendered":"https:\/\/ccla.org\/?p=11774"},"modified":"2026-03-26T14:56:57","modified_gmt":"2026-03-26T18:56:57","slug":"bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian","status":"publish","type":"post","link":"https:\/\/ccla.org\/fr\/communique-de-presse\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/","title":{"rendered":"Le projet de loi C-9 \u00e9tait cens\u00e9 lutter contre la haine. Au lieu de cela, il est adopt\u00e9 \u00e0 la h\u00e2te par le Parlement et menace les droits de tous les Canadiens."},"content":{"rendered":"<div id=\"fws_6a0470ae594eb\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a0470ae59a26\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row full-width-section\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"true\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><div class=\"row-bg-overlay row-bg-layer\" style=\"background: rgba(0,0,0,0.3); background: linear-gradient(to bottom,rgba(0,0,0,0.3) 0%,rgba(238,238,238,0.01) 100%);  opacity: 0.5; \"><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 10px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n<div class=\"divider-wrap\" data-alignment=\"default\"><div style=\"height: 30px;\" class=\"divider\"><\/div><\/div>\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a0470ae59dc3\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>MONTR\u00c9AL - Ana\u00efs Bussi\u00e8res McNicoll, directrice du Programme des libert\u00e9s fondamentales, a fait la d\u00e9claration suivante apr\u00e8s que le gouvernement f\u00e9d\u00e9ral a forc\u00e9 le Comit\u00e9 de la justice de la Chambre des communes \u00e0 terminer l'\u00e9tude du projet de loi sur l'acc\u00e8s \u00e0 l'information et la protection des renseignements personnels.\u00a0<em>Lutte contre la haine<\/em>:<\/p>\n<p>Hier, le gouvernement f\u00e9d\u00e9ral a forc\u00e9 la\u00a0<a href=\"https:\/\/www.ourcommons.ca\/DocumentViewer\/en\/45-1\/JUST\/meeting-20\/notice\" target=\"_blank\" rel=\"noopener\">Commission de la justice de la Chambre des communes<\/a>\u00a0(JUST) pour terminer l'\u00e9tude de\u00a0<a href=\"https:\/\/www.parl.ca\/legisinfo\/en\/bill\/44-2\/c-9\" target=\"_blank\" rel=\"noopener\">Projet de loi C-9<\/a>\u00a0- les <em>Lutte contre la haine<\/em>.<\/p>\n<p>Il n'y a plus de d\u00e9bat, il faut simplement faire avancer les choses, malgr\u00e9 les nombreuses imperfections du projet de loi.<\/p>\n<p>Le gouvernement est maintenant pr\u00eat \u00e0 faire adopter le projet de loi C-9, en donnant \u00e0 la Chambre des communes un maximum de deux jours pour la phase du rapport et la troisi\u00e8me lecture.<\/p>\n<p>Cela devrait alarmer tous les Canadiens qui se soucient des pratiques d\u00e9mocratiques et de la libert\u00e9 d'expression.<\/p>\n<p>L'antis\u00e9mitisme, l'islamophobie et le racisme sont en hausse. Les communaut\u00e9s de ce pays sont inqui\u00e8tes et m\u00e9ritent d'\u00eatre prot\u00e9g\u00e9es. Mais le projet de loi C-9 ne r\u00e9sout pas ce probl\u00e8me complexe. Au contraire, il donne au gouvernement un instrument contondant qui, selon l'histoire, sera retourn\u00e9 contre les personnes m\u00eames qu'il est cens\u00e9 aider.<\/p>\n<p>Plus de 40 organisations de la soci\u00e9t\u00e9 civile, repr\u00e9sentant des communaut\u00e9s d'origines diverses,\u00a0<a href=\"https:\/\/www.hilltimes.com\/story\/2025\/10\/15\/civil-liberties-groups-urge-liberals-to-withdraw-vague-anti-hate-bill-that-opposition-mps-say-is-trying-to-lower-the-bar-for-prosecution\/477063\/\" target=\"_blank\" rel=\"noopener\">a exprim\u00e9 de s\u00e9rieuses inqui\u00e9tudes au sujet de ce projet de loi \u00e0 l'automne<\/a>. Ils ont averti que sa formulation vague pourrait \u00eatre utilis\u00e9e pour criminaliser les protestations pacifiques et r\u00e9duire au silence les expressions impopulaires. Au lieu de r\u00e9pondre de mani\u00e8re significative \u00e0 ces pr\u00e9occupations, le processus tronqu\u00e9 de la commission n'a que tr\u00e8s peu am\u00e9lior\u00e9 le projet de loi et l'a m\u00eame aggrav\u00e9 en supprimant la d\u00e9fense religieuse de bonne foi du Code p\u00e9nal sans la remplacer par quoi que ce soit d'ad\u00e9quat.<\/p>\n<p>Les modifications du droit p\u00e9nal qui affectent la libert\u00e9 d'expression m\u00e9ritent un examen minutieux, et non des jeux de pouvoir proc\u00e9duraux. En for\u00e7ant la commission \u00e0 conclure sans r\u00e9pondre aux pr\u00e9occupations soulev\u00e9es par des dizaines d'organisations confessionnelles et de la soci\u00e9t\u00e9 civile, le gouvernement envoie un message : faire passer cette loi est plus important que de faire en sorte qu'elle soit correcte.<\/p>\n<p>Ce n'est pas ainsi que l'on combat la haine ou que l'on \u00e9tablit la confiance avec des communaut\u00e9s d\u00e9j\u00e0 vuln\u00e9rables.<\/p>\n<p>Les lois punitives qui criminalisent l'expression n'arr\u00eatent pas la haine. Elles donnent aux gouvernements un outil qui, \u00e0 maintes reprises, est utilis\u00e9 contre les peuples autochtones, les communaut\u00e9s racialis\u00e9es, les manifestants et les dissidents.<\/p>\n<p>Nous demandons instamment aux parlementaires de rejeter tout texte l\u00e9gislatif qui porte atteinte aux normes d\u00e9mocratiques et aux libert\u00e9s civiles des citoyens canadiens.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\t\t<div id=\"fws_6a0470ae5a0a3\"  data-column-margin=\"default\" data-midnight=\"dark\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: 0px; padding-bottom: 0px; \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t\n\t\t<div id=\"fws_6a0470ae5a41c\"  data-column-margin=\"default\" data-midnight=\"dark\" data-top-percent=\"1%\" data-bottom-percent=\"1%\"  class=\"wpb_row vc_row-fluid vc_row\"  style=\"padding-top: calc(100vw * 0.01); padding-bottom: calc(100vw * 0.01); \"><div class=\"row-bg-wrap\" data-bg-animation=\"none\" data-bg-animation-delay=\"\" data-bg-overlay=\"false\"><div class=\"inner-wrap row-bg-layer\" ><div class=\"row-bg viewport-desktop\"  style=\"\"><\/div><\/div><\/div><div class=\"row_col_wrap_12 col span_12 dark left\">\n\t<div  class=\"vc_col-sm-12 wpb_column column_container vc_column_container col no-extra-padding inherit_tablet inherit_phone\"  data-padding-pos=\"all\" data-has-bg-color=\"false\" data-bg-color=\"\" data-bg-opacity=\"1\" data-animation=\"\" data-delay=\"0\" >\n\t\t<div class=\"vc_column-inner\" >\n\t\t\t<div class=\"wpb_wrapper\">\n\t\t\t\t<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >\u00c0 propos de l\u2019association canadienne sur les libert\u00e9s civiles<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p class=\"translation-block\">L\u2019ACLC est un organisme ind\u00e9pendant \u00e0 but non lucratif qui compte des sympathisant.e.s dans tout le pays. Fond\u00e9 en 1964, c\u2019est un organisme qui \u0153uvre \u00e0 l\u2019\u00e9chelle du Canada \u00e0 la protection des droits et des libert\u00e9s civiles de toute sa population.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les m\u00e9dias<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Pour d&#039;autres commentaires, veuillez nous contacter \u00e0\u00a0<a href=\"mailto:media@ccla.org\"><u>media@ccla.org<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n<h3 style=\"color: #ef770e;text-align: left\" class=\"vc_custom_heading vc_do_custom_heading\" >Pour les mises \u00e0 jour en direct<\/h3>\n<div class=\"wpb_text_column wpb_content_element\" >\n\t<div class=\"wpb_wrapper\">\n\t\t<p>Veuillez continuer \u00e0 vous r\u00e9f\u00e9rer \u00e0\u00a0<a href=\"https:\/\/ccla.org\/fr\/the-latest\/\" rel=\"noopener\">cette page<\/a>\u00a0et \u00e0 nos plateformes de m\u00e9dias sociaux. On est dessus\u00a0<a href=\"https:\/\/www.instagram.com\/cancivlib\/?hl=en\" target=\"_blank\" rel=\"noopener\"><u>Instagram<\/u><\/a>,\u00a0<a href=\"http:\/\/facebook.com\/cancivlib\/\" target=\"_blank\" rel=\"noopener\"><u>Facebook<\/u><\/a>, <a href=\"https:\/\/twitter.com\/cancivlib\" target=\"_blank\" rel=\"noopener\"><u>Twitter<\/u><\/a> et <a href=\"https:\/\/bsky.app\/profile\/cancivlib.bsky.social\" target=\"_blank\" rel=\"noopener\"><u>Ciel bleu<\/u><\/a>.<\/p>\n\t<\/div>\n<\/div>\n\n\n\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>\n\n\t\t\t<\/div> \n\t\t<\/div>\n\t<\/div> \n<\/div><\/div>","protected":false},"excerpt":{"rendered":"MONTR\u00c9AL - Ana\u00efs Bussi\u00e8res McNicoll, directrice du Programme des libert\u00e9s fondamentales, a fait la d\u00e9claration suivante apr\u00e8s que le gouvernement f\u00e9d\u00e9ral a forc\u00e9 le Comit\u00e9 de la justice de la Chambre des communes \u00e0 terminer l'\u00e9tude de...","protected":false},"author":4,"featured_media":7422,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[105,31,8,107],"tags":[],"class_list":{"0":"post-11774","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-criminal-prohibitions-on-speech","8":"category-fundamental-freedoms","9":"category-press-release","10":"category-regulation-of-online-expression"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Bill C-9 Was Supposed to Fight Hate. Instead, It&#039;s Being Rushed Through Parliament and Threatens the Rights of Every Canadian - CCLA<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/ccla.org\/fr\/communique-de-presse\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/\" \/>\n<meta property=\"og:locale\" content=\"fr_CA\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bill C-9 Was Supposed to Fight Hate. Instead, It&#039;s Being Rushed Through Parliament and Threatens the Rights of Every Canadian - CCLA\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ccla.org\/fr\/communique-de-presse\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/\" \/>\n<meta property=\"og:site_name\" content=\"CCLA\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-12T16:12:57+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-26T18:56:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/ccla.org\/wp-content\/uploads\/2022\/04\/Emergencies-Act-Header-1024x410.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"410\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"CCLA\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"CCLA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Estimation du temps de lecture\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/\",\"url\":\"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/\",\"name\":\"Bill C-9 Was Supposed to Fight Hate. Instead, It's Being Rushed Through Parliament and Threatens the Rights of Every Canadian - CCLA\",\"isPartOf\":{\"@id\":\"https:\/\/ccla.org\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2022\/04\/Emergencies-Act-Header.png\",\"datePublished\":\"2026-03-12T16:12:57+00:00\",\"dateModified\":\"2026-03-26T18:56:57+00:00\",\"author\":{\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d\"},\"breadcrumb\":{\"@id\":\"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#breadcrumb\"},\"inLanguage\":\"fr-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#primaryimage\",\"url\":\"https:\/\/ccla.org\/wp-content\/uploads\/2022\/04\/Emergencies-Act-Header.png\",\"contentUrl\":\"https:\/\/ccla.org\/wp-content\/uploads\/2022\/04\/Emergencies-Act-Header.png\",\"width\":2000,\"height\":800},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/ccla.org\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PRESS RELEASES\",\"item\":\"https:\/\/ccla.org\/category\/press-release\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Bill C-9 Was Supposed to Fight Hate. Instead, It&#8217;s Being Rushed Through Parliament and Threatens the Rights of Every Canadian\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/ccla.org\/#website\",\"url\":\"https:\/\/ccla.org\/\",\"name\":\"CCLA\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/ccla.org\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-CA\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d\",\"name\":\"CCLA\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-CA\",\"@id\":\"https:\/\/ccla.org\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g\",\"caption\":\"CCLA\"},\"url\":\"https:\/\/ccla.org\/fr\/author\/ccla\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bill C-9 Was Supposed to Fight Hate. Instead, It's Being Rushed Through Parliament and Threatens the Rights of Every Canadian - CCLA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/ccla.org\/fr\/communique-de-presse\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/","og_locale":"fr_CA","og_type":"article","og_title":"Bill C-9 Was Supposed to Fight Hate. Instead, It's Being Rushed Through Parliament and Threatens the Rights of Every Canadian - CCLA","og_url":"https:\/\/ccla.org\/fr\/communique-de-presse\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/","og_site_name":"CCLA","article_published_time":"2026-03-12T16:12:57+00:00","article_modified_time":"2026-03-26T18:56:57+00:00","og_image":[{"width":1024,"height":410,"url":"https:\/\/ccla.org\/wp-content\/uploads\/2022\/04\/Emergencies-Act-Header-1024x410.png","type":"image\/png"}],"author":"CCLA","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"CCLA","Estimation du temps de lecture":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/","url":"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/","name":"Bill C-9 Was Supposed to Fight Hate. Instead, It's Being Rushed Through Parliament and Threatens the Rights of Every Canadian - CCLA","isPartOf":{"@id":"https:\/\/ccla.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#primaryimage"},"image":{"@id":"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#primaryimage"},"thumbnailUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2022\/04\/Emergencies-Act-Header.png","datePublished":"2026-03-12T16:12:57+00:00","dateModified":"2026-03-26T18:56:57+00:00","author":{"@id":"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d"},"breadcrumb":{"@id":"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#breadcrumb"},"inLanguage":"fr-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/"]}]},{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#primaryimage","url":"https:\/\/ccla.org\/wp-content\/uploads\/2022\/04\/Emergencies-Act-Header.png","contentUrl":"https:\/\/ccla.org\/wp-content\/uploads\/2022\/04\/Emergencies-Act-Header.png","width":2000,"height":800},{"@type":"BreadcrumbList","@id":"https:\/\/ccla.org\/press-release\/bill-c-9-was-supposed-to-fight-hate-instead-its-being-rushed-through-parliament-and-threatens-the-rights-of-every-canadian\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ccla.org\/"},{"@type":"ListItem","position":2,"name":"PRESS RELEASES","item":"https:\/\/ccla.org\/category\/press-release\/"},{"@type":"ListItem","position":3,"name":"Bill C-9 Was Supposed to Fight Hate. Instead, It&#8217;s Being Rushed Through Parliament and Threatens the Rights of Every Canadian"}]},{"@type":"WebSite","@id":"https:\/\/ccla.org\/#website","url":"https:\/\/ccla.org\/","name":"CCLA","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ccla.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-CA"},{"@type":"Person","@id":"https:\/\/ccla.org\/#\/schema\/person\/8340210ad747e50e21e040b101a55d8d","name":"CCLA","image":{"@type":"ImageObject","inLanguage":"fr-CA","@id":"https:\/\/ccla.org\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8b870059ce8f35a3967c509e5d35c55a?s=96&d=blank&r=g","caption":"CCLA"},"url":"https:\/\/ccla.org\/fr\/author\/ccla\/"}]}},"_links":{"self":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/11774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/comments?post=11774"}],"version-history":[{"count":4,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/11774\/revisions"}],"predecessor-version":[{"id":11778,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/posts\/11774\/revisions\/11778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media\/7422"}],"wp:attachment":[{"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/media?parent=11774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/categories?post=11774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ccla.org\/fr\/wp-json\/wp\/v2\/tags?post=11774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}